{"id":8746,"date":"2024-08-19T08:56:54","date_gmt":"2024-08-19T11:56:54","guid":{"rendered":"https:\/\/www.fcaglp.unlp.edu.ar\/?page_id=8746"},"modified":"2024-08-19T08:56:55","modified_gmt":"2024-08-19T11:56:55","slug":"efemerides-astronomicas-2021","status":"publish","type":"page","link":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/","title":{"rendered":"Efem\u00e9rides Astron\u00f3micas 2021"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fcaglp.unlp.edu.ar\/uploads\/docs\/equinoccios_y_solsticios_2021.docx\">Equinoccios y Solsticios 2021<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fcaglp.unlp.edu.ar\/uploads\/docs\/eclipses_sol_y_luna_2021.pdf\">Eclipses de Sol y Luna 2021<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fcaglp.unlp.edu.ar\/uploads\/docs\/sol_2021.pdf\">Sol 2021<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fcaglp.unlp.edu.ar\/uploads\/docs\/luna_2021.pdf\">Luna 2021<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fcaglp.unlp.edu.ar\/uploads\/docs\/mercurio_2021.pdf\">Mercurio 2021<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fcaglp.unlp.edu.ar\/uploads\/docs\/venus_2021.pdf\">Venus 2021<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fcaglp.unlp.edu.ar\/uploads\/docs\/marte_2021.pdf\">Marte 2021<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fcaglp.unlp.edu.ar\/uploads\/docs\/jupiter_2021.pdf\">J\u00fapiter 2021<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fcaglp.unlp.edu.ar\/uploads\/docs\/saturno_2021.pdf\">Saturno 2021<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fcaglp.unlp.edu.ar\/uploads\/docs\/urano_2021.pdf\">Urano 2021<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fcaglp.unlp.edu.ar\/uploads\/docs\/neptuno_2021.pdf\">Neptuno 2021<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Equinoccios y Solsticios 2021 Eclipses de Sol y Luna 2021 Sol 2021 Luna 2021 Mercurio 2021 Venus 2021 Marte 2021 J\u00fapiter 2021 Saturno 2021 Urano 2021 Neptuno 2021<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-8746","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Equinoccios y Solsticios 2021 Eclipses de Sol y Luna 2021 Sol 2021 Luna 2021 Mercurio 2021 Venus 2021 Marte 2021 J\u00fapiter 2021 Saturno 2021 Urano 2021 Neptuno 2021\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"FCAGLP - UNLP - Facultad de Ciencias Astron\u00f3micas y Geof\u00edsica\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Efem\u00e9rides Astron\u00f3micas 2021 - FCAGLP - UNLP\" \/>\n\t\t<meta property=\"og:description\" content=\"Equinoccios y Solsticios 2021 Eclipses de Sol y Luna 2021 Sol 2021 Luna 2021 Mercurio 2021 Venus 2021 Marte 2021 J\u00fapiter 2021 Saturno 2021 Urano 2021 Neptuno 2021\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.fcaglp.unlp.edu.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-07-at-16.59.26.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.fcaglp.unlp.edu.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-07-at-16.59.26.jpeg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-08-19T11:56:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-19T11:56:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Efem\u00e9rides Astron\u00f3micas 2021 - FCAGLP - UNLP\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Equinoccios y Solsticios 2021 Eclipses de Sol y Luna 2021 Sol 2021 Luna 2021 Mercurio 2021 Venus 2021 Marte 2021 J\u00fapiter 2021 Saturno 2021 Urano 2021 Neptuno 2021\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.fcaglp.unlp.edu.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-07-at-16.59.26.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/index.php\\\/efemerides-astronomicas-2021\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/index.php\\\/efemerides-astronomicas-2021\\\/#listItem\",\"name\":\"Efem\\u00e9rides Astron\\u00f3micas 2021\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/index.php\\\/efemerides-astronomicas-2021\\\/#listItem\",\"position\":2,\"name\":\"Efem\\u00e9rides Astron\\u00f3micas 2021\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/#organization\",\"name\":\"Facultad de Ciencias Astron\\u00f3micas y Geof\\u00edsicas\",\"description\":\"Facultad de Ciencias Astron\\u00f3micas y Geof\\u00edsica\",\"url\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/WhatsApp-Image-2021-12-07-at-16.59.26.jpeg\",\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/index.php\\\/efemerides-astronomicas-2021\\\/#organizationLogo\",\"width\":210,\"height\":74},\"image\":{\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/index.php\\\/efemerides-astronomicas-2021\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/index.php\\\/efemerides-astronomicas-2021\\\/#webpage\",\"url\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/index.php\\\/efemerides-astronomicas-2021\\\/\",\"name\":\"Efem\\u00e9rides Astron\\u00f3micas 2021 - FCAGLP - UNLP\",\"description\":\"Equinoccios y Solsticios 2021 Eclipses de Sol y Luna 2021 Sol 2021 Luna 2021 Mercurio 2021 Venus 2021 Marte 2021 J\\u00fapiter 2021 Saturno 2021 Urano 2021 Neptuno 2021\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/index.php\\\/efemerides-astronomicas-2021\\\/#breadcrumblist\"},\"datePublished\":\"2024-08-19T08:56:54-03:00\",\"dateModified\":\"2024-08-19T08:56:55-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/#website\",\"url\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/\",\"name\":\"Facultad de Ciencias Astron\\u00f3micas y Geof\\u00edsicas | UNLP\",\"alternateName\":\"FCAGLP | UNLP\",\"description\":\"Facultad de Ciencias Astron\\u00f3micas y Geof\\u00edsica\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fcaglp.unlp.edu.ar\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Efem\u00e9rides Astron\u00f3micas 2021 - FCAGLP - UNLP","description":"Equinoccios y Solsticios 2021 Eclipses de Sol y Luna 2021 Sol 2021 Luna 2021 Mercurio 2021 Venus 2021 Marte 2021 J\u00fapiter 2021 Saturno 2021 Urano 2021 Neptuno 2021","canonical_url":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.fcaglp.unlp.edu.ar#listItem","position":1,"name":"Home","item":"https:\/\/www.fcaglp.unlp.edu.ar","nextItem":{"@type":"ListItem","@id":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/#listItem","name":"Efem\u00e9rides Astron\u00f3micas 2021"}},{"@type":"ListItem","@id":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/#listItem","position":2,"name":"Efem\u00e9rides Astron\u00f3micas 2021","previousItem":{"@type":"ListItem","@id":"https:\/\/www.fcaglp.unlp.edu.ar#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/www.fcaglp.unlp.edu.ar\/#organization","name":"Facultad de Ciencias Astron\u00f3micas y Geof\u00edsicas","description":"Facultad de Ciencias Astron\u00f3micas y Geof\u00edsica","url":"https:\/\/www.fcaglp.unlp.edu.ar\/","logo":{"@type":"ImageObject","url":"https:\/\/www.fcaglp.unlp.edu.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-07-at-16.59.26.jpeg","@id":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/#organizationLogo","width":210,"height":74},"image":{"@id":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/#webpage","url":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/","name":"Efem\u00e9rides Astron\u00f3micas 2021 - FCAGLP - UNLP","description":"Equinoccios y Solsticios 2021 Eclipses de Sol y Luna 2021 Sol 2021 Luna 2021 Mercurio 2021 Venus 2021 Marte 2021 J\u00fapiter 2021 Saturno 2021 Urano 2021 Neptuno 2021","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/www.fcaglp.unlp.edu.ar\/#website"},"breadcrumb":{"@id":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/#breadcrumblist"},"datePublished":"2024-08-19T08:56:54-03:00","dateModified":"2024-08-19T08:56:55-03:00"},{"@type":"WebSite","@id":"https:\/\/www.fcaglp.unlp.edu.ar\/#website","url":"https:\/\/www.fcaglp.unlp.edu.ar\/","name":"Facultad de Ciencias Astron\u00f3micas y Geof\u00edsicas | UNLP","alternateName":"FCAGLP | UNLP","description":"Facultad de Ciencias Astron\u00f3micas y Geof\u00edsica","inLanguage":"es-AR","publisher":{"@id":"https:\/\/www.fcaglp.unlp.edu.ar\/#organization"}}]},"og:locale":"es_ES","og:site_name":"FCAGLP - UNLP - Facultad de Ciencias Astron\u00f3micas y Geof\u00edsica","og:type":"article","og:title":"Efem\u00e9rides Astron\u00f3micas 2021 - FCAGLP - UNLP","og:description":"Equinoccios y Solsticios 2021 Eclipses de Sol y Luna 2021 Sol 2021 Luna 2021 Mercurio 2021 Venus 2021 Marte 2021 J\u00fapiter 2021 Saturno 2021 Urano 2021 Neptuno 2021","og:url":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/","og:image":"https:\/\/www.fcaglp.unlp.edu.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-07-at-16.59.26.jpeg","og:image:secure_url":"https:\/\/www.fcaglp.unlp.edu.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-07-at-16.59.26.jpeg","article:published_time":"2024-08-19T11:56:54+00:00","article:modified_time":"2024-08-19T11:56:55+00:00","twitter:card":"summary","twitter:title":"Efem\u00e9rides Astron\u00f3micas 2021 - FCAGLP - UNLP","twitter:description":"Equinoccios y Solsticios 2021 Eclipses de Sol y Luna 2021 Sol 2021 Luna 2021 Mercurio 2021 Venus 2021 Marte 2021 J\u00fapiter 2021 Saturno 2021 Urano 2021 Neptuno 2021","twitter:image":"https:\/\/www.fcaglp.unlp.edu.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-07-at-16.59.26.jpeg"},"aioseo_meta_data":[],"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.fcaglp.unlp.edu.ar\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEfem\u00e9rides Astron\u00f3micas 2021\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.fcaglp.unlp.edu.ar"},{"label":"Efem\u00e9rides Astron\u00f3micas 2021","link":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/efemerides-astronomicas-2021\/"}],"_links":{"self":[{"href":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/pages\/8746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=8746"}],"version-history":[{"count":1,"href":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/pages\/8746\/revisions"}],"predecessor-version":[{"id":8748,"href":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/pages\/8746\/revisions\/8748"}],"wp:attachment":[{"href":"https:\/\/www.fcaglp.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=8746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}